{"id":4086,"count":1,"description":"","link":"https:\/\/los-angeles-trend.com\/uk\/tag\/the-return-of-ironside","name":"The Return of Ironside","slug":"the-return-of-ironside","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/los-angeles-trend.com\/uk\/wp-json\/wp\/v2\/tags\/4086","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/los-angeles-trend.com\/uk\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/los-angeles-trend.com\/uk\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/los-angeles-trend.com\/uk\/wp-json\/wp\/v2\/posts?tags=4086"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}