{"id":3589,"count":1,"description":"","link":"https:\/\/los-angeles-trend.com\/uk\/tag\/teatralnyj-aktor","name":"\u0442\u0435\u0430\u0442\u0440\u0430\u043b\u044c\u043d\u0438\u0439 \u0430\u043a\u0442\u043e\u0440","slug":"teatralnyj-aktor","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/los-angeles-trend.com\/uk\/wp-json\/wp\/v2\/tags\/3589","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/los-angeles-trend.com\/uk\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/los-angeles-trend.com\/uk\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/los-angeles-trend.com\/uk\/wp-json\/wp\/v2\/posts?tags=3589"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}