{"id":3548,"count":1,"description":"","link":"https:\/\/los-angeles-trend.com\/uk\/tag\/johnnye-allee-albom","name":"Johnnye Allee \u0430\u043b\u044c\u0431\u043e\u043c","slug":"johnnye-allee-albom","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/los-angeles-trend.com\/uk\/wp-json\/wp\/v2\/tags\/3548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/los-angeles-trend.com\/uk\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/los-angeles-trend.com\/uk\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/los-angeles-trend.com\/uk\/wp-json\/wp\/v2\/posts?tags=3548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}