{"id":3399,"count":1,"description":"","link":"https:\/\/los-angeles-trend.com\/uk\/tag\/am-records","name":"A&amp;M Records","slug":"am-records","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/los-angeles-trend.com\/uk\/wp-json\/wp\/v2\/tags\/3399","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/los-angeles-trend.com\/uk\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/los-angeles-trend.com\/uk\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/los-angeles-trend.com\/uk\/wp-json\/wp\/v2\/posts?tags=3399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}