{"id":2320,"count":1,"description":"","link":"https:\/\/los-angeles-trend.com\/uk\/tag\/filmy-marvel","name":"\u0444\u0456\u043b\u044c\u043c\u0438 Marvel","slug":"filmy-marvel","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/los-angeles-trend.com\/uk\/wp-json\/wp\/v2\/tags\/2320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/los-angeles-trend.com\/uk\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/los-angeles-trend.com\/uk\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/los-angeles-trend.com\/uk\/wp-json\/wp\/v2\/posts?tags=2320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}