{"id":2211,"count":1,"description":"","link":"https:\/\/los-angeles-trend.com\/uk\/tag\/the-warner-grand-theatre","name":"The Warner Grand Theatre","slug":"the-warner-grand-theatre","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/los-angeles-trend.com\/uk\/wp-json\/wp\/v2\/tags\/2211","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/los-angeles-trend.com\/uk\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/los-angeles-trend.com\/uk\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/los-angeles-trend.com\/uk\/wp-json\/wp\/v2\/posts?tags=2211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}