{"id":1460,"count":1,"description":"","link":"https:\/\/los-angeles-trend.com\/uk\/tag\/teatr-mav-pershyj-u-sviti-konsolnyj-balkon","name":"\u0422\u0435\u0430\u0442\u0440 \u043c\u0430\u0432 \u043f\u0435\u0440\u0448\u0438\u0439 \u0443 \u0441\u0432\u0456\u0442\u0456 \u043a\u043e\u043d\u0441\u043e\u043b\u044c\u043d\u0438\u0439 \u0431\u0430\u043b\u043a\u043e\u043d","slug":"teatr-mav-pershyj-u-sviti-konsolnyj-balkon","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/los-angeles-trend.com\/uk\/wp-json\/wp\/v2\/tags\/1460","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/los-angeles-trend.com\/uk\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/los-angeles-trend.com\/uk\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/los-angeles-trend.com\/uk\/wp-json\/wp\/v2\/posts?tags=1460"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}