{"id":940,"count":1,"description":"","link":"https:\/\/los-angeles-trend.com\/ru\/tag\/%d1%88%d0%b0%d0%b2%d0%ba%d0%b0%d1%82-%d0%bc%d0%b8%d1%80%d0%b7%d0%b8%d1%91%d0%b5%d0%b2-%d1%81%d1%83%d0%bc%d0%b5%d0%bb-%d1%83%d0%bb%d1%83%d1%87%d1%88%d0%b8%d1%82%d1%8c-%d1%8d%d0%ba%d0%be%d0%bd%d0%be","name":"\u0428\u0430\u0432\u043a\u0430\u0442 \u041c\u0438\u0440\u0437\u0438\u0451\u0435\u0432 \u0441\u0443\u043c\u0435\u043b \u0443\u043b\u0443\u0447\u0448\u0438\u0442\u044c \u044d\u043a\u043e\u043d\u043e\u043c\u0438\u043a\u0443 \u0432 \u0441\u0442\u0440\u0430\u043d\u0435","slug":"%d1%88%d0%b0%d0%b2%d0%ba%d0%b0%d1%82-%d0%bc%d0%b8%d1%80%d0%b7%d0%b8%d1%91%d0%b5%d0%b2-%d1%81%d1%83%d0%bc%d0%b5%d0%bb-%d1%83%d0%bb%d1%83%d1%87%d1%88%d0%b8%d1%82%d1%8c-%d1%8d%d0%ba%d0%be%d0%bd%d0%be","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/los-angeles-trend.com\/ru\/wp-json\/wp\/v2\/tags\/940","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/los-angeles-trend.com\/ru\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/los-angeles-trend.com\/ru\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/los-angeles-trend.com\/ru\/wp-json\/wp\/v2\/posts?tags=940"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}