{"id":2340,"count":1,"description":"","link":"https:\/\/los-angeles-trend.com\/ru\/tag\/rol-zheleznogo-cheloveka","name":"\u0440\u043e\u043b\u044c \u0416\u0435\u043b\u0435\u0437\u043d\u043e\u0433\u043e \u0447\u0435\u043b\u043e\u0432\u0435\u043a\u0430","slug":"rol-zheleznogo-cheloveka","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/los-angeles-trend.com\/ru\/wp-json\/wp\/v2\/tags\/2340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/los-angeles-trend.com\/ru\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/los-angeles-trend.com\/ru\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/los-angeles-trend.com\/ru\/wp-json\/wp\/v2\/posts?tags=2340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}