{"id":1967,"count":1,"description":"","link":"https:\/\/los-angeles-trend.com\/ru\/tag\/luchshie-albomy-metallica","name":"\u043b\u0443\u0447\u0448\u0438\u0435 \u0430\u043b\u044c\u0431\u043e\u043c\u044b Metallica","slug":"luchshie-albomy-metallica","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/los-angeles-trend.com\/ru\/wp-json\/wp\/v2\/tags\/1967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/los-angeles-trend.com\/ru\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/los-angeles-trend.com\/ru\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/los-angeles-trend.com\/ru\/wp-json\/wp\/v2\/posts?tags=1967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}