{"id":1811,"count":1,"description":"","link":"https:\/\/los-angeles-trend.com\/ru\/tag\/mesto-provedeniya-konczertov","name":"\u043c\u0435\u0441\u0442\u043e \u043f\u0440\u043e\u0432\u0435\u0434\u0435\u043d\u0438\u044f \u043a\u043e\u043d\u0446\u0435\u0440\u0442\u043e\u0432","slug":"mesto-provedeniya-konczertov","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/los-angeles-trend.com\/ru\/wp-json\/wp\/v2\/tags\/1811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/los-angeles-trend.com\/ru\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/los-angeles-trend.com\/ru\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/los-angeles-trend.com\/ru\/wp-json\/wp\/v2\/posts?tags=1811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}