{"id":1604,"date":"2024-02-14T12:28:49","date_gmt":"2024-02-14T20:28:49","guid":{"rendered":"https:\/\/los-angeles-trend.com\/?p=1604"},"modified":"2024-02-14T12:32:46","modified_gmt":"2024-02-14T20:32:46","slug":"7-umnyh-strategij-borby-s-sherstyu-domashnih-zhivotnyh-i-zapahami-v-vashej-kvartire","status":"publish","type":"post","link":"https:\/\/los-angeles-trend.com\/ru\/articles-1604-7-umnyh-strategij-borby-s-sherstyu-domashnih-zhivotnyh-i-zapahami-v-vashej-kvartire","title":{"rendered":"7 \u0443\u043c\u043d\u044b\u0445 \u0441\u0442\u0440\u0430\u0442\u0435\u0433\u0438\u0439 \u0431\u043e\u0440\u044c\u0431\u044b \u0441 \u0448\u0435\u0440\u0441\u0442\u044c\u044e \u0434\u043e\u043c\u0430\u0448\u043d\u0438\u0445 \u0436\u0438\u0432\u043e\u0442\u043d\u044b\u0445 \u0438 \u0437\u0430\u043f\u0430\u0445\u0430\u043c\u0438 \u0432 \u0432\u0430\u0448\u0435\u0439 \u043a\u0432\u0430\u0440\u0442\u0438\u0440\u0435"},"content":{"rendered":"\n<p>\u0416\u0438\u0437\u043d\u044c \u0432 \u0433\u0430\u0440\u043c\u043e\u043d\u0438\u0438 \u0441 \u0434\u043e\u043c\u0430\u0448\u043d\u0438\u043c\u0438 \u0436\u0438\u0432\u043e\u0442\u043d\u044b\u043c\u0438 \u0432 \u043a\u0432\u0430\u0440\u0442\u0438\u0440\u0435 \u0434\u0430\u0440\u0438\u0442 \u043d\u0435\u043f\u0440\u0435\u0432\u0437\u043e\u0439\u0434\u0435\u043d\u043d\u0443\u044e \u0440\u0430\u0434\u043e\u0441\u0442\u044c \u0438 \u043e\u0431\u0449\u0435\u043d\u0438\u0435, \u043f\u0440\u0435\u0432\u0440\u0430\u0449\u0430\u044f \u043e\u0431\u044b\u0447\u043d\u043e\u0435 \u0436\u0438\u043b\u043e\u0435 \u043f\u0440\u043e\u0441\u0442\u0440\u0430\u043d\u0441\u0442\u0432\u043e \u0432 \u043e\u0431\u0449\u0443\u044e \u0433\u0430\u0432\u0430\u043d\u044c \u0441\u0447\u0430\u0441\u0442\u044c\u044f. \u041e\u0434\u043d\u0430\u043a\u043e \u044d\u0442\u043e \u0441\u043e\u0432\u043c\u0435\u0441\u0442\u043d\u043e\u0435 \u043f\u0440\u043e\u0436\u0438\u0432\u0430\u043d\u0438\u0435 \u0441\u0432\u044f\u0437\u0430\u043d\u043e \u0441\u043e \u0441\u0432\u043e\u0438\u043c\u0438 \u0442\u0440\u0443\u0434\u043d\u043e\u0441\u0442\u044f\u043c\u0438, \u0432 \u0447\u0430\u0441\u0442\u043d\u043e\u0441\u0442\u0438, \u0432 \u0431\u043e\u0440\u044c\u0431\u0435 \u0441 \u043d\u0435\u0438\u0437\u0431\u0435\u0436\u043d\u043e\u0439 \u0448\u0435\u0440\u0441\u0442\u044c\u044e \u0434\u043e\u043c\u0430\u0448\u043d\u0438\u0445 \u0436\u0438\u0432\u043e\u0442\u043d\u044b\u0445 \u0438 \u0432\u044b\u0440\u0430\u0437\u0438\u0442\u0435\u043b\u044c\u043d\u044b\u043c\u0438 \u0437\u0430\u043f\u0430\u0445\u0430\u043c\u0438, \u0441\u043e\u043f\u0440\u043e\u0432\u043e\u0436\u0434\u0430\u044e\u0449\u0438\u043c\u0438 \u043d\u0430\u0448\u0438\u0445 \u043f\u0443\u0448\u0438\u0441\u0442\u044b\u0445 \u0434\u0440\u0443\u0437\u0435\u0439. \u0414\u043e\u043c\u0430\u0448\u043d\u0438\u0435 \u0436\u0438\u0432\u043e\u0442\u043d\u044b\u0435, \u043d\u0435\u0441\u043e\u043c\u043d\u0435\u043d\u043d\u043e, \u043e\u0431\u043e\u0433\u0430\u0449\u0430\u044e\u0442 \u043d\u0430\u0448\u0443 \u0436\u0438\u0437\u043d\u044c, \u043d\u043e \u0431\u0435\u0437 \u0434\u043e\u043b\u0436\u043d\u043e\u0433\u043e \u0443\u0445\u043e\u0434\u0430 \u0438\u0445 \u0448\u0435\u0440\u0441\u0442\u044c \u0438 \u0437\u0430\u043f\u0430\u0445\u0438 \u043c\u043e\u0433\u0443\u0442 \u0431\u044b\u0441\u0442\u0440\u043e \u0432\u043e\u0446\u0430\u0440\u0438\u0442\u044c\u0441\u044f \u0432 \u043a\u0432\u0430\u0440\u0442\u0438\u0440\u0435, \u0432\u043b\u0438\u044f\u044f \u043d\u0430 \u043e\u0431\u0449\u0438\u0439 \u043a\u043e\u043c\u0444\u043e\u0440\u0442 \u0438 \u0447\u0438\u0441\u0442\u043e\u0442\u0443 \u0441\u0440\u0435\u0434\u044b \u043e\u0431\u0438\u0442\u0430\u043d\u0438\u044f. \u041a \u0441\u0447\u0430\u0441\u0442\u044c\u044e, \u0441\u0443\u0449\u0435\u0441\u0442\u0432\u0443\u044e\u0442 \u044d\u0444\u0444\u0435\u043a\u0442\u0438\u0432\u043d\u044b\u0435 \u0441\u0442\u0440\u0430\u0442\u0435\u0433\u0438\u0438 \u0438 \u0440\u0430\u0437\u0443\u043c\u043d\u044b\u0435 \u0440\u0435\u0448\u0435\u043d\u0438\u044f, \u043a\u043e\u0442\u043e\u0440\u044b\u0435 \u043c\u043e\u0433\u0443\u0442 \u043f\u043e\u043c\u043e\u0447\u044c \u0441\u043c\u044f\u0433\u0447\u0438\u0442\u044c \u044d\u0442\u0438 \u043f\u0440\u043e\u0431\u043b\u0435\u043c\u044b, \u043f\u043e\u0437\u0432\u043e\u043b\u044f\u044f \u0432\u043b\u0430\u0434\u0435\u043b\u044c\u0446\u0430\u043c \u0434\u043e\u043c\u0430\u0448\u043d\u0438\u0445 \u0436\u0438\u0432\u043e\u0442\u043d\u044b\u0445 \u043d\u0430\u0441\u043b\u0430\u0436\u0434\u0430\u0442\u044c\u0441\u044f \u043b\u0443\u0447\u0448\u0438\u043c \u0438\u0437 \u043e\u0431\u043e\u0438\u0445 \u043c\u0438\u0440\u043e\u0432 \u2013 \u0447\u0438\u0441\u0442\u044b\u043c, \u0441\u0432\u0435\u0436\u0438\u043c \u0434\u043e\u043c\u043e\u043c \u0438 \u0431\u0435\u0437\u0443\u0441\u043b\u043e\u0432\u043d\u043e\u0439 \u043b\u044e\u0431\u043e\u0432\u044c\u044e \u0441\u0432\u043e\u0438\u0445 \u0434\u043e\u043c\u0430\u0448\u043d\u0438\u0445 \u0436\u0438\u0432\u043e\u0442\u043d\u044b\u0445. \u0412\u043e\u0442 \u0441\u0435\u043c\u044c \u0432\u0430\u0436\u043d\u044b\u0445 \u0441\u043e\u0432\u0435\u0442\u043e\u0432 \u043e\u0442 <a href=\"https:\/\/www.livecleantoday.com\/apartment-cleaning\/\" data-type=\"link\" data-id=\"https:\/\/www.livecleantoday.com\/apartment-cleaning\/\" target=\"_blank\" rel=\"noopener\">\u043f\u0440\u043e\u0444\u0435\u0441\u0441\u0438\u043e\u043d\u0430\u043b\u044c\u043d\u044b\u0445 \u0443\u0431\u043e\u0440\u0449\u0438\u043a\u043e\u0432 \u043a\u0432\u0430\u0440\u0442\u0438\u0440<\/a>, \u043d\u0430\u043f\u0440\u0430\u0432\u043b\u0435\u043d\u043d\u044b\u0445 \u043d\u0430 \u0442\u043e, \u0447\u0442\u043e\u0431\u044b \u043a\u043e\u043d\u0442\u0440\u043e\u043b\u0438\u0440\u043e\u0432\u0430\u0442\u044c \u0448\u0435\u0440\u0441\u0442\u044c \u0434\u043e\u043c\u0430\u0448\u043d\u0438\u0445 \u0436\u0438\u0432\u043e\u0442\u043d\u044b\u0445 \u0438 \u0437\u0430\u043f\u0430\u0445\u0438, \u0447\u0442\u043e\u0431\u044b \u0432\u0430\u0448\u0430 \u043a\u0432\u0430\u0440\u0442\u0438\u0440\u0430 \u043e\u0441\u0442\u0430\u0432\u0430\u043b\u0430\u0441\u044c \u0440\u0430\u0434\u0443\u0448\u043d\u044b\u043c \u0438 \u043f\u0440\u0438\u044f\u0442\u043d\u044b\u043c \u043c\u0435\u0441\u0442\u043e\u043c \u0434\u043b\u044f \u0432\u0441\u0435\u0445 \u0435\u0435 \u043e\u0431\u0438\u0442\u0430\u0442\u0435\u043b\u0435\u0439.<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_74 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<label for=\"ez-toc-cssicon-toggle-item-6a04d3a767b12\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a04d3a767b12\"  aria-label=\"Toggle\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/los-angeles-trend.com\/ru\/articles-1604-7-umnyh-strategij-borby-s-sherstyu-domashnih-zhivotnyh-i-zapahami-v-vashej-kvartire\/#1_%D0%98%D0%BD%D0%B2%D0%B5%D1%81%D1%82%D0%B8%D1%80%D1%83%D0%B9%D1%82%D0%B5_%D0%B2_%D0%B2%D1%8B%D1%81%D0%BE%D0%BA%D0%BE%D0%BA%D0%B0%D1%87%D0%B5%D1%81%D1%82%D0%B2%D0%B5%D0%BD%D0%BD%D1%8B%D0%B9_%D0%BF%D1%8B%D0%BB%D0%B5%D1%81%D0%BE%D1%81\" >1. \u0418\u043d\u0432\u0435\u0441\u0442\u0438\u0440\u0443\u0439\u0442\u0435 \u0432 \u0432\u044b\u0441\u043e\u043a\u043e\u043a\u0430\u0447\u0435\u0441\u0442\u0432\u0435\u043d\u043d\u044b\u0439 \u043f\u044b\u043b\u0435\u0441\u043e\u0441<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/los-angeles-trend.com\/ru\/articles-1604-7-umnyh-strategij-borby-s-sherstyu-domashnih-zhivotnyh-i-zapahami-v-vashej-kvartire\/#2_%D0%A3%D1%81%D1%82%D0%B0%D0%BD%D0%BE%D0%B2%D0%B8%D1%82%D0%B5_%D0%BF%D0%BE%D1%81%D0%BB%D0%B5%D0%B4%D0%BE%D0%B2%D0%B0%D1%82%D0%B5%D0%BB%D1%8C%D0%BD%D1%8B%D0%B9_%D0%BF%D0%BE%D1%80%D1%8F%D0%B4%D0%BE%D0%BA_%D1%83%D0%B1%D0%BE%D1%80%D0%BA%D0%B8\" >2. \u0423\u0441\u0442\u0430\u043d\u043e\u0432\u0438\u0442\u0435 \u043f\u043e\u0441\u043b\u0435\u0434\u043e\u0432\u0430\u0442\u0435\u043b\u044c\u043d\u044b\u0439 \u043f\u043e\u0440\u044f\u0434\u043e\u043a \u0443\u0431\u043e\u0440\u043a\u0438<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/los-angeles-trend.com\/ru\/articles-1604-7-umnyh-strategij-borby-s-sherstyu-domashnih-zhivotnyh-i-zapahami-v-vashej-kvartire\/#3_%D0%98%D1%81%D0%BF%D0%BE%D0%BB%D1%8C%D0%B7%D1%83%D0%B9%D1%82%D0%B5_%D0%BC%D0%BE%D1%8E%D1%89%D0%B8%D0%B5%D1%81%D1%8F_%D0%BF%D0%BB%D0%B5%D0%B4%D1%8B_%D0%B8_%D1%87%D0%B5%D1%85%D0%BB%D1%8B_%D0%B4%D0%BB%D1%8F_%D0%BC%D0%B5%D0%B1%D0%B5%D0%BB%D0%B8\" >3. \u0418\u0441\u043f\u043e\u043b\u044c\u0437\u0443\u0439\u0442\u0435 \u043c\u043e\u044e\u0449\u0438\u0435\u0441\u044f \u043f\u043b\u0435\u0434\u044b \u0438 \u0447\u0435\u0445\u043b\u044b \u0434\u043b\u044f \u043c\u0435\u0431\u0435\u043b\u0438<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/los-angeles-trend.com\/ru\/articles-1604-7-umnyh-strategij-borby-s-sherstyu-domashnih-zhivotnyh-i-zapahami-v-vashej-kvartire\/#4_%D0%A3%D0%BB%D1%83%D1%87%D1%88%D0%B0%D0%B9%D1%82%D0%B5_%D0%BA%D0%B0%D1%87%D0%B5%D1%81%D1%82%D0%B2%D0%BE_%D0%B2%D0%BE%D0%B7%D0%B4%D1%83%D1%85%D0%B0_%D0%BF%D1%80%D0%B8_%D0%BF%D0%BE%D0%BC%D0%BE%D1%89%D0%B8_%D0%BE%D1%87%D0%B8%D1%81%D1%82%D0%B8%D1%82%D0%B5%D0%BB%D0%B5%D0%B9_%D0%B8_%D0%B2%D0%B5%D0%BD%D1%82%D0%B8%D0%BB%D1%8F%D1%86%D0%B8%D0%B8\" >4. \u0423\u043b\u0443\u0447\u0448\u0430\u0439\u0442\u0435 \u043a\u0430\u0447\u0435\u0441\u0442\u0432\u043e \u0432\u043e\u0437\u0434\u0443\u0445\u0430 \u043f\u0440\u0438 \u043f\u043e\u043c\u043e\u0449\u0438 \u043e\u0447\u0438\u0441\u0442\u0438\u0442\u0435\u043b\u0435\u0439 \u0438 \u0432\u0435\u043d\u0442\u0438\u043b\u044f\u0446\u0438\u0438<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/los-angeles-trend.com\/ru\/articles-1604-7-umnyh-strategij-borby-s-sherstyu-domashnih-zhivotnyh-i-zapahami-v-vashej-kvartire\/#5_%D0%9D%D0%B5%D0%B9%D1%82%D1%80%D0%B0%D0%BB%D0%B8%D0%B7%D0%B8%D1%80%D1%83%D0%B9%D1%82%D0%B5_%D0%B7%D0%B0%D0%BF%D0%B0%D1%85%D0%B8_%D0%BD%D0%B5%D0%BF%D0%BE%D1%81%D1%80%D0%B5%D0%B4%D1%81%D1%82%D0%B2%D0%B5%D0%BD%D0%BD%D0%BE_%D0%B2%D0%BE%D0%B7%D0%BB%D0%B5_%D0%B8%D1%85_%D0%B8%D1%81%D1%82%D0%BE%D1%87%D0%BD%D0%B8%D0%BA%D0%B0\" >5. \u041d\u0435\u0439\u0442\u0440\u0430\u043b\u0438\u0437\u0438\u0440\u0443\u0439\u0442\u0435 \u0437\u0430\u043f\u0430\u0445\u0438 \u043d\u0435\u043f\u043e\u0441\u0440\u0435\u0434\u0441\u0442\u0432\u0435\u043d\u043d\u043e \u0432\u043e\u0437\u043b\u0435 \u0438\u0445 \u0438\u0441\u0442\u043e\u0447\u043d\u0438\u043a\u0430<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/los-angeles-trend.com\/ru\/articles-1604-7-umnyh-strategij-borby-s-sherstyu-domashnih-zhivotnyh-i-zapahami-v-vashej-kvartire\/#6_%D0%A3%D0%B4%D0%B5%D0%BB%D0%B8%D1%82%D0%B5_%D0%B2%D1%80%D0%B5%D0%BC%D1%8F_%D1%83%D0%B1%D0%BE%D1%80%D0%BA%D0%B8_%D0%B7%D0%BE%D0%BD_%D0%B3%D0%B4%D0%B5_%D0%B6%D0%B8%D0%B2%D1%83%D1%82_%D0%B4%D0%BE%D0%BC%D0%B0%D1%88%D0%BD%D0%B8%D0%B5_%D0%B6%D0%B8%D0%B2%D0%BE%D1%82%D0%BD%D1%8B%D0%B5\" >6. \u0423\u0434\u0435\u043b\u0438\u0442\u0435 \u0432\u0440\u0435\u043c\u044f \u0443\u0431\u043e\u0440\u043a\u0438 \u0437\u043e\u043d, \u0433\u0434\u0435 \u0436\u0438\u0432\u0443\u0442 \u0434\u043e\u043c\u0430\u0448\u043d\u0438\u0435 \u0436\u0438\u0432\u043e\u0442\u043d\u044b\u0435<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/los-angeles-trend.com\/ru\/articles-1604-7-umnyh-strategij-borby-s-sherstyu-domashnih-zhivotnyh-i-zapahami-v-vashej-kvartire\/#7_%D0%92%D1%8B%D0%B1%D0%B8%D1%80%D0%B0%D0%B9%D1%82%D0%B5_%D0%BF%D1%80%D0%B8%D1%80%D0%BE%D0%B4%D0%BD%D1%8B%D0%B5_%D0%BC%D0%B5%D1%82%D0%BE%D0%B4%D1%8B_%D0%B4%D0%B5%D0%B7%D0%BE%D0%B4%D0%BE%D1%80%D0%B0%D1%86%D0%B8%D0%B8\" >7. \u0412\u044b\u0431\u0438\u0440\u0430\u0439\u0442\u0435 \u043f\u0440\u0438\u0440\u043e\u0434\u043d\u044b\u0435 \u043c\u0435\u0442\u043e\u0434\u044b \u0434\u0435\u0437\u043e\u0434\u043e\u0440\u0430\u0446\u0438\u0438<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"1_%D0%98%D0%BD%D0%B2%D0%B5%D1%81%D1%82%D0%B8%D1%80%D1%83%D0%B9%D1%82%D0%B5_%D0%B2_%D0%B2%D1%8B%D1%81%D0%BE%D0%BA%D0%BE%D0%BA%D0%B0%D1%87%D0%B5%D1%81%D1%82%D0%B2%D0%B5%D0%BD%D0%BD%D1%8B%D0%B9_%D0%BF%D1%8B%D0%BB%D0%B5%D1%81%D0%BE%D1%81\"><\/span>1. \u0418\u043d\u0432\u0435\u0441\u0442\u0438\u0440\u0443\u0439\u0442\u0435 \u0432 \u0432\u044b\u0441\u043e\u043a\u043e\u043a\u0430\u0447\u0435\u0441\u0442\u0432\u0435\u043d\u043d\u044b\u0439 \u043f\u044b\u043b\u0435\u0441\u043e\u0441<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>\u0427\u0442\u043e\u0431\u044b \u0438\u043c\u0435\u0442\u044c \u0434\u043e\u043c\u0430\u0448\u043d\u0435\u0433\u043e \u043f\u0438\u0442\u043e\u043c\u0446\u0430, \u043d\u0443\u0436\u0435\u043d \u043d\u0430\u0434\u0435\u0436\u043d\u044b\u0439 \u043f\u044b\u043b\u0435\u0441\u043e\u0441, \u0441\u043f\u043e\u0441\u043e\u0431\u043d\u044b\u0439 \u0443\u0434\u0430\u043b\u044f\u0442\u044c \u0448\u0435\u0440\u0441\u0442\u044c \u0434\u043e\u043c\u0430\u0448\u043d\u0438\u0445 \u0436\u0438\u0432\u043e\u0442\u043d\u044b\u0445 \u0441 \u0440\u0430\u0437\u043d\u044b\u0445 \u043f\u043e\u0432\u0435\u0440\u0445\u043d\u043e\u0441\u0442\u0435\u0439. \u0412\u044b\u0431\u0438\u0440\u0430\u0439\u0442\u0435 \u043f\u044b\u043b\u0435\u0441\u043e\u0441 \u0441 \u043d\u0430\u0434\u0435\u0436\u043d\u044b\u043c \u0432\u0441\u0430\u0441\u044b\u0432\u0430\u043d\u0438\u0435\u043c, \u0441\u043f\u0435\u0446\u0438\u0430\u043b\u044c\u043d\u044b\u043c\u0438 \u043d\u0430\u0441\u0430\u0434\u043a\u0430\u043c\u0438 \u0434\u043b\u044f \u0448\u0435\u0440\u0441\u0442\u0438 \u0434\u043e\u043c\u0430\u0448\u043d\u0438\u0445 \u0436\u0438\u0432\u043e\u0442\u043d\u044b\u0445 \u0438 \u0444\u0438\u043b\u044c\u0442\u0440\u0430\u043c\u0438 HEPA, \u0441\u043f\u043e\u0441\u043e\u0431\u043d\u044b\u043c\u0438 \u0437\u0430\u0434\u0435\u0440\u0436\u0438\u0432\u0430\u0442\u044c \u043c\u0435\u043b\u043a\u0438\u0435 \u0447\u0430\u0441\u0442\u0438\u0446\u044b, \u0442\u0430\u043a\u0438\u0435 \u043a\u0430\u043a \u0448\u0435\u0440\u0441\u0442\u044c \u0438 \u043f\u0435\u0440\u0445\u043e\u0442\u044c. \u0420\u0435\u0433\u0443\u043b\u044f\u0440\u043d\u043e\u0435 \u0438\u0441\u043f\u043e\u043b\u044c\u0437\u043e\u0432\u0430\u043d\u0438\u0435 \u0442\u0430\u043a\u043e\u0433\u043e \u043f\u044b\u043b\u0435\u0441\u043e\u0441\u0430 \u0434\u043b\u044f \u043e\u0447\u0438\u0441\u0442\u043a\u0438 \u043f\u043e\u043b\u043e\u0432, \u043c\u044f\u0433\u043a\u043e\u0439 \u043c\u0435\u0431\u0435\u043b\u0438 \u0438 \u0434\u0430\u0436\u0435 \u043e\u0442\u0434\u0435\u043b\u043a\u0438 \u043e\u043a\u043e\u043d \u043c\u043e\u0436\u0435\u0442 \u0437\u043d\u0430\u0447\u0438\u0442\u0435\u043b\u044c\u043d\u043e \u0441\u043d\u0438\u0437\u0438\u0442\u044c \u043d\u0430\u043b\u0438\u0447\u0438\u0435 \u0448\u0435\u0440\u0441\u0442\u0438 \u0434\u043e\u043c\u0430\u0448\u043d\u0438\u0445 \u0436\u0438\u0432\u043e\u0442\u043d\u044b\u0445 \u0432 \u0432\u0430\u0448\u0435\u043c \u0436\u0438\u043b\u043e\u043c \u043f\u043e\u043c\u0435\u0449\u0435\u043d\u0438\u0438, \u0441\u043e\u0437\u0434\u0430\u0432\u0430\u044f \u0431\u043e\u043b\u0435\u0435 \u0447\u0438\u0441\u0442\u0443\u044e \u0441\u0440\u0435\u0434\u0443 \u0431\u0435\u0437 \u0430\u043b\u043b\u0435\u0440\u0433\u0435\u043d\u043e\u0432.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"2_%D0%A3%D1%81%D1%82%D0%B0%D0%BD%D0%BE%D0%B2%D0%B8%D1%82%D0%B5_%D0%BF%D0%BE%D1%81%D0%BB%D0%B5%D0%B4%D0%BE%D0%B2%D0%B0%D1%82%D0%B5%D0%BB%D1%8C%D0%BD%D1%8B%D0%B9_%D0%BF%D0%BE%D1%80%D1%8F%D0%B4%D0%BE%D0%BA_%D1%83%D0%B1%D0%BE%D1%80%D0%BA%D0%B8\"><\/span>2. \u0423\u0441\u0442\u0430\u043d\u043e\u0432\u0438\u0442\u0435 \u043f\u043e\u0441\u043b\u0435\u0434\u043e\u0432\u0430\u0442\u0435\u043b\u044c\u043d\u044b\u0439 \u043f\u043e\u0440\u044f\u0434\u043e\u043a \u0443\u0431\u043e\u0440\u043a\u0438 <span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>\u041e\u0434\u043d\u0438\u043c \u0438\u0437 \u0441\u0430\u043c\u044b\u0445 \u044d\u0444\u0444\u0435\u043a\u0442\u0438\u0432\u043d\u044b\u0445 \u0441\u043f\u043e\u0441\u043e\u0431\u043e\u0432 \u0431\u043e\u0440\u044c\u0431\u044b \u0441 \u043b\u0438\u0448\u043d\u0435\u0439 \u0448\u0435\u0440\u0441\u0442\u044c\u044e \u0438 \u043d\u0435\u043f\u0440\u0438\u044f\u0442\u043d\u044b\u043c \u0437\u0430\u043f\u0430\u0445\u043e\u043c \u0434\u043e\u043c\u0430\u0448\u043d\u0438\u0445 \u0436\u0438\u0432\u043e\u0442\u043d\u044b\u0445 \u044f\u0432\u043b\u044f\u0435\u0442\u0441\u044f \u0440\u0435\u0433\u0443\u043b\u044f\u0440\u043d\u044b\u0439 \u0443\u0445\u043e\u0434. \u0427\u0430\u0441\u0442\u044b\u0435 \u0441\u0435\u0430\u043d\u0441\u044b \u0440\u0430\u0441\u0447\u0435\u0441\u044b\u0432\u0430\u043d\u0438\u044f \u043f\u043e\u043c\u043e\u0433\u0430\u044e\u0442 \u0443\u0434\u0430\u043b\u0438\u0442\u044c \u0440\u044b\u0445\u043b\u0443\u044e \u0448\u0435\u0440\u0441\u0442\u044c \u043d\u0435\u043f\u043e\u0441\u0440\u0435\u0434\u0441\u0442\u0432\u0435\u043d\u043d\u043e \u0438\u0437 \u0432\u0430\u0448\u0435\u0433\u043e \u043f\u0438\u0442\u043e\u043c\u0446\u0430, \u043f\u0440\u0435\u0436\u0434\u0435 \u0447\u0435\u043c \u043e\u043d\u0430 \u0443\u0441\u043f\u0435\u0435\u0442 \u0440\u0430\u0437\u043b\u0435\u0442\u0435\u0442\u044c\u0441\u044f \u043f\u043e \u043a\u0432\u0430\u0440\u0442\u0438\u0440\u0435. \u0414\u043b\u044f \u043d\u0435\u043a\u043e\u0442\u043e\u0440\u044b\u0445 \u0434\u043e\u043c\u0430\u0448\u043d\u0438\u0445 \u0436\u0438\u0432\u043e\u0442\u043d\u044b\u0445 \u043f\u0440\u043e\u0444\u0435\u0441\u0441\u0438\u043e\u043d\u0430\u043b\u044c\u043d\u044b\u0439 \u0443\u0445\u043e\u0434 \u043c\u043e\u0436\u0435\u0442 \u043f\u0440\u0435\u0434\u043e\u0441\u0442\u0430\u0432\u0438\u0442\u044c \u0434\u043e\u043f\u043e\u043b\u043d\u0438\u0442\u0435\u043b\u044c\u043d\u044b\u0435 \u043f\u0440\u0435\u0438\u043c\u0443\u0449\u0435\u0441\u0442\u0432\u0430 \u0432 \u0443\u043f\u0440\u0430\u0432\u043b\u0435\u043d\u0438\u0438 \u043b\u0438\u043d\u044c\u043a\u043e\u0439 \u0438 \u043e\u0431\u0435\u0441\u043f\u0435\u0447\u0435\u043d\u0438\u0438 \u043e\u043f\u0442\u0438\u043c\u0430\u043b\u044c\u043d\u043e\u0439 \u0433\u0438\u0433\u0438\u0435\u043d\u044b. \u042d\u0442\u0438 \u0441\u0435\u0430\u043d\u0441\u044b \u0443\u0445\u043e\u0434\u0430 \u043d\u0435 \u0442\u043e\u043b\u044c\u043a\u043e \u0443\u043b\u0443\u0447\u0448\u0430\u044e\u0442 \u0441\u0430\u043c\u043e\u0447\u0443\u0432\u0441\u0442\u0432\u0438\u0435 \u0432\u0430\u0448\u0435\u0433\u043e \u043f\u0438\u0442\u043e\u043c\u0446\u0430, \u043d\u043e \u0438 \u0437\u043d\u0430\u0447\u0438\u0442\u0435\u043b\u044c\u043d\u043e \u0443\u043c\u0435\u043d\u044c\u0448\u0430\u044e\u0442 \u043a\u043e\u043b\u0438\u0447\u0435\u0441\u0442\u0432\u043e \u0448\u0435\u0440\u0441\u0442\u0438 \u0438 \u0437\u0430\u043f\u0430\u0445\u043e\u0432, \u0441\u0432\u044f\u0437\u0430\u043d\u043d\u044b\u0445 \u0441 \u0434\u043e\u043c\u0430\u0448\u043d\u0438\u043c\u0438 \u0436\u0438\u0432\u043e\u0442\u043d\u044b\u043c\u0438, \u0432 \u0432\u0430\u0448\u0435\u043c \u0434\u043e\u043c\u0435.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"3_%D0%98%D1%81%D0%BF%D0%BE%D0%BB%D1%8C%D0%B7%D1%83%D0%B9%D1%82%D0%B5_%D0%BC%D0%BE%D1%8E%D1%89%D0%B8%D0%B5%D1%81%D1%8F_%D0%BF%D0%BB%D0%B5%D0%B4%D1%8B_%D0%B8_%D1%87%D0%B5%D1%85%D0%BB%D1%8B_%D0%B4%D0%BB%D1%8F_%D0%BC%D0%B5%D0%B1%D0%B5%D0%BB%D0%B8\"><\/span>3. \u0418\u0441\u043f\u043e\u043b\u044c\u0437\u0443\u0439\u0442\u0435 \u043c\u043e\u044e\u0449\u0438\u0435\u0441\u044f \u043f\u043b\u0435\u0434\u044b \u0438 \u0447\u0435\u0445\u043b\u044b \u0434\u043b\u044f \u043c\u0435\u0431\u0435\u043b\u0438<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>\u0417\u0430\u0449\u0438\u0442\u0430 \u043c\u0435\u0431\u0435\u043b\u0438 \u0441 \u043f\u043e\u043c\u043e\u0449\u044c\u044e \u043c\u043e\u044e\u0449\u0438\u0445\u0441\u044f \u0447\u0435\u0445\u043b\u043e\u0432 \u044f\u0432\u043b\u044f\u0435\u0442\u0441\u044f \u043f\u0440\u0430\u043a\u0442\u0438\u0447\u0435\u0441\u043a\u0438\u043c \u043f\u043e\u0434\u0445\u043e\u0434\u043e\u043c \u043a \u0431\u043e\u0440\u044c\u0431\u0435 \u0441 \u0448\u0435\u0440\u0441\u0442\u044c\u044e \u0438 \u0437\u0430\u043f\u0430\u0445\u0430\u043c\u0438 \u0434\u043e\u043c\u0430\u0448\u043d\u0438\u0445 \u0436\u0438\u0432\u043e\u0442\u043d\u044b\u0445. \u042d\u0442\u0438 \u0437\u0430\u0449\u0438\u0442\u043d\u044b\u0435 \u0441\u043b\u043e\u0438 \u043c\u043e\u0436\u043d\u043e \u043b\u0435\u0433\u043a\u043e \u0441\u043d\u044f\u0442\u044c \u0438 \u043f\u043e\u0441\u0442\u0438\u0440\u0430\u0442\u044c, \u044d\u0444\u0444\u0435\u043a\u0442\u0438\u0432\u043d\u043e \u0437\u0430\u0445\u0432\u0430\u0442\u044b\u0432\u0430\u044f \u0438 \u0443\u0434\u0430\u043b\u044f\u044f \u0448\u0435\u0440\u0441\u0442\u044c \u0434\u043e\u043c\u0430\u0448\u043d\u0438\u0445 \u0436\u0438\u0432\u043e\u0442\u043d\u044b\u0445 \u0438 \u043f\u0440\u0435\u0434\u043e\u0442\u0432\u0440\u0430\u0449\u0430\u044f \u043f\u0440\u043e\u043d\u0438\u043a\u043d\u043e\u0432\u0435\u043d\u0438\u0435 \u0437\u0430\u043f\u0430\u0445\u043e\u0432 \u0432 \u043c\u0435\u0431\u0435\u043b\u044c. \u0412\u044b\u0431\u043e\u0440 \u043f\u0440\u043e\u0447\u043d\u044b\u0445, \u0443\u0434\u043e\u0431\u043d\u044b\u0445 \u0434\u043b\u044f \u0434\u043e\u043c\u0430\u0448\u043d\u0438\u0445 \u0436\u0438\u0432\u043e\u0442\u043d\u044b\u0445 \u0442\u043a\u0430\u043d\u0435\u0439 \u0438 \u0441\u043e\u0431\u043b\u044e\u0434\u0435\u043d\u0438\u044f \u0440\u0435\u0433\u0443\u043b\u044f\u0440\u043d\u043e\u0433\u043e \u0433\u0440\u0430\u0444\u0438\u043a\u0430 \u0441\u0442\u0438\u0440\u043a\u0438 \u044f\u0432\u043b\u044f\u0435\u0442\u0441\u044f \u043a\u043b\u044e\u0447\u0435\u0432\u044b\u043c \u0434\u043b\u044f \u0442\u043e\u0433\u043e, \u0447\u0442\u043e\u0431\u044b \u0432\u0430\u0448\u0430 \u043c\u0435\u0431\u0435\u043b\u044c \u043e\u0441\u0442\u0430\u0432\u0430\u043b\u0430\u0441\u044c \u0441\u0432\u0435\u0436\u0435\u0439 \u0438 \u043f\u0440\u0438\u0432\u043b\u0435\u043a\u0430\u0442\u0435\u043b\u044c\u043d\u043e\u0439.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"4_%D0%A3%D0%BB%D1%83%D1%87%D1%88%D0%B0%D0%B9%D1%82%D0%B5_%D0%BA%D0%B0%D1%87%D0%B5%D1%81%D1%82%D0%B2%D0%BE_%D0%B2%D0%BE%D0%B7%D0%B4%D1%83%D1%85%D0%B0_%D0%BF%D1%80%D0%B8_%D0%BF%D0%BE%D0%BC%D0%BE%D1%89%D0%B8_%D0%BE%D1%87%D0%B8%D1%81%D1%82%D0%B8%D1%82%D0%B5%D0%BB%D0%B5%D0%B9_%D0%B8_%D0%B2%D0%B5%D0%BD%D1%82%D0%B8%D0%BB%D1%8F%D1%86%D0%B8%D0%B8\"><\/span>4. \u0423\u043b\u0443\u0447\u0448\u0430\u0439\u0442\u0435 \u043a\u0430\u0447\u0435\u0441\u0442\u0432\u043e \u0432\u043e\u0437\u0434\u0443\u0445\u0430 \u043f\u0440\u0438 \u043f\u043e\u043c\u043e\u0449\u0438 \u043e\u0447\u0438\u0441\u0442\u0438\u0442\u0435\u043b\u0435\u0439 \u0438 \u0432\u0435\u043d\u0442\u0438\u043b\u044f\u0446\u0438\u0438<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>\u041f\u043e\u0434\u0434\u0435\u0440\u0436\u0430\u043d\u0438\u0435 \u043e\u043f\u0442\u0438\u043c\u0430\u043b\u044c\u043d\u043e\u0433\u043e \u043a\u0430\u0447\u0435\u0441\u0442\u0432\u0430 \u0432\u043e\u0437\u0434\u0443\u0445\u0430 \u0438\u043c\u0435\u0435\u0442 \u0440\u0435\u0448\u0430\u044e\u0449\u0435\u0435 \u0437\u043d\u0430\u0447\u0435\u043d\u0438\u0435 \u0432 \u043a\u0432\u0430\u0440\u0442\u0438\u0440\u0435, \u0433\u0434\u0435 \u0440\u0430\u0437\u0440\u0435\u0448\u0435\u043d\u043e \u043f\u0440\u043e\u0436\u0438\u0432\u0430\u043d\u0438\u0435 \u0441 \u0436\u0438\u0432\u043e\u0442\u043d\u044b\u043c\u0438. \u0418\u043d\u0432\u0435\u0441\u0442\u0438\u0440\u043e\u0432\u0430\u043d\u0438\u0435 \u0432 \u0432\u043e\u0437\u0434\u0443\u0445\u043e\u043e\u0447\u0438\u0441\u0442\u0438\u0442\u0435\u043b\u044c, \u043e\u0441\u043d\u0430\u0449\u0435\u043d\u043d\u044b\u0439 \u0444\u0438\u043b\u044c\u0442\u0440\u043e\u043c HEPA, \u043c\u043e\u0436\u0435\u0442 \u0437\u043d\u0430\u0447\u0438\u0442\u0435\u043b\u044c\u043d\u043e \u0443\u043c\u0435\u043d\u044c\u0448\u0438\u0442\u044c \u043a\u043e\u043b\u0438\u0447\u0435\u0441\u0442\u0432\u043e \u0430\u043b\u043b\u0435\u0440\u0433\u0435\u043d\u043e\u0432 \u0432 \u0432\u043e\u0437\u0434\u0443\u0445\u0435 \u0434\u043e\u043c\u0430\u0448\u043d\u0438\u0445 \u0436\u0438\u0432\u043e\u0442\u043d\u044b\u0445, \u0432 \u0447\u0430\u0441\u0442\u043d\u043e\u0441\u0442\u0438 \u043f\u0435\u0440\u0445\u043e\u0442\u0438 \u0438 \u0448\u0435\u0440\u0441\u0442\u0438. \u041a\u0440\u043e\u043c\u0435 \u0442\u043e\u0433\u043e, \u0435\u0441\u0442\u0435\u0441\u0442\u0432\u0435\u043d\u043d\u0430\u044f \u0432\u0435\u043d\u0442\u0438\u043b\u044f\u0446\u0438\u044f \u0447\u0435\u0440\u0435\u0437 \u043e\u0442\u043a\u0440\u044b\u0442\u044b\u0435 \u043e\u043a\u043d\u0430 \u043f\u043e\u043c\u043e\u0436\u0435\u0442 \u0440\u0430\u0437\u0431\u0430\u0432\u0438\u0442\u044c \u0438 \u0440\u0430\u0441\u0441\u0435\u044f\u0442\u044c \u0437\u0430\u043f\u0430\u0445\u0438 \u0434\u043e\u043c\u0430\u0448\u043d\u0438\u0445 \u0436\u0438\u0432\u043e\u0442\u043d\u044b\u0445, \u043e\u0441\u0432\u0435\u0436\u0430\u044f \u0432\u043e\u0437\u0434\u0443\u0445 \u0432 \u043f\u043e\u043c\u0435\u0449\u0435\u043d\u0438\u0438. \u0422\u0430\u043a\u043e\u0435 \u0441\u043e\u0447\u0435\u0442\u0430\u043d\u0438\u0435 \u043e\u0447\u0438\u0441\u0442\u043a\u0438 \u0432\u043e\u0437\u0434\u0443\u0445\u0430 \u0438 \u0432\u0435\u043d\u0442\u0438\u043b\u044f\u0446\u0438\u0438 \u0441\u043e\u0437\u0434\u0430\u0435\u0442 \u0431\u043e\u043b\u0435\u0435 \u0437\u0434\u043e\u0440\u043e\u0432\u0443\u044e \u0441\u0440\u0435\u0434\u0443 \u043e\u0431\u0438\u0442\u0430\u043d\u0438\u044f \u043a\u0430\u043a \u0434\u043b\u044f \u0434\u043e\u043c\u0430\u0448\u043d\u0438\u0445 \u0436\u0438\u0432\u043e\u0442\u043d\u044b\u0445, \u0442\u0430\u043a \u0438 \u043b\u044e\u0434\u0435\u0439.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"5_%D0%9D%D0%B5%D0%B9%D1%82%D1%80%D0%B0%D0%BB%D0%B8%D0%B7%D0%B8%D1%80%D1%83%D0%B9%D1%82%D0%B5_%D0%B7%D0%B0%D0%BF%D0%B0%D1%85%D0%B8_%D0%BD%D0%B5%D0%BF%D0%BE%D1%81%D1%80%D0%B5%D0%B4%D1%81%D1%82%D0%B2%D0%B5%D0%BD%D0%BD%D0%BE_%D0%B2%D0%BE%D0%B7%D0%BB%D0%B5_%D0%B8%D1%85_%D0%B8%D1%81%D1%82%D0%BE%D1%87%D0%BD%D0%B8%D0%BA%D0%B0\"><\/span>5. \u041d\u0435\u0439\u0442\u0440\u0430\u043b\u0438\u0437\u0438\u0440\u0443\u0439\u0442\u0435 \u0437\u0430\u043f\u0430\u0445\u0438 \u043d\u0435\u043f\u043e\u0441\u0440\u0435\u0434\u0441\u0442\u0432\u0435\u043d\u043d\u043e \u0432\u043e\u0437\u043b\u0435 \u0438\u0445 \u0438\u0441\u0442\u043e\u0447\u043d\u0438\u043a\u0430<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>\u042d\u0444\u0444\u0435\u043a\u0442\u0438\u0432\u043d\u0430\u044f \u0431\u043e\u0440\u044c\u0431\u0430 \u0441 \u0437\u0430\u043f\u0430\u0445\u0430\u043c\u0438 \u0434\u043e\u043c\u0430\u0448\u043d\u0438\u0445 \u0436\u0438\u0432\u043e\u0442\u043d\u044b\u0445 \u043f\u043e\u0434\u0440\u0430\u0437\u0443\u043c\u0435\u0432\u0430\u0435\u0442 \u0431\u043e\u0440\u044c\u0431\u0443 \u0441 \u0438\u0445 \u043f\u0440\u043e\u0438\u0441\u0445\u043e\u0436\u0434\u0435\u043d\u0438\u0435\u043c. \u0420\u0435\u0433\u0443\u043b\u044f\u0440\u043d\u0430\u044f \u0447\u0438\u0441\u0442\u043a\u0430 \u043f\u043e\u0434\u0441\u0442\u0438\u043b\u043e\u043a, \u0438\u0433\u0440\u0443\u0448\u0435\u043a \u0438 \u0430\u043a\u0441\u0435\u0441\u0441\u0443\u0430\u0440\u043e\u0432 \u0434\u043b\u044f \u0434\u043e\u043c\u0430\u0448\u043d\u0438\u0445 \u0436\u0438\u0432\u043e\u0442\u043d\u044b\u0445 \u043c\u0438\u043d\u0438\u043c\u0438\u0437\u0438\u0440\u0443\u0435\u0442 \u043e\u0431\u0440\u0430\u0437\u043e\u0432\u0430\u043d\u0438\u0435 \u0437\u0430\u043f\u0430\u0445\u0430. \u0418\u0441\u043f\u043e\u043b\u044c\u0437\u0443\u0439\u0442\u0435 \u044d\u043d\u0437\u0438\u043c\u043d\u044b\u0435 \u043e\u0447\u0438\u0441\u0442\u0438\u0442\u0435\u043b\u0438 \u043f\u0440\u0438 \u043b\u044e\u0431\u044b\u0445 \u043d\u0435\u0441\u0447\u0430\u0441\u0442\u043d\u044b\u0445 \u0441\u043b\u0443\u0447\u0430\u044f\u0445, \u0447\u0442\u043e\u0431\u044b \u0442\u0449\u0430\u0442\u0435\u043b\u044c\u043d\u043e \u0443\u0441\u0442\u0440\u0430\u043d\u0438\u0442\u044c \u0437\u0430\u043f\u0430\u0445\u0438, \u043f\u0440\u0435\u0434\u043e\u0442\u0432\u0440\u0430\u0449\u0430\u044f \u043f\u043e\u0432\u0442\u043e\u0440\u043d\u043e\u0435 \u043f\u043e\u044f\u0432\u043b\u0435\u043d\u0438\u0435 \u043c\u0430\u0440\u043a\u0438\u0440\u043e\u0432\u043a\u0438. \u041f\u043e\u0434\u0434\u0435\u0440\u0436\u043a\u0430 \u0447\u0438\u0441\u0442\u043e\u0433\u043e \u043b\u043e\u0442\u043a\u0430 \u0438 \u043f\u043e\u0438\u0441\u043a \u0432\u0430\u0440\u0438\u0430\u043d\u0442\u043e\u0432 \u043d\u0435\u0439\u0442\u0440\u0430\u043b\u0438\u0437\u0443\u044e\u0449\u0435\u0439 \u0437\u0430\u043f\u0430\u0445 \u043f\u043e\u0434\u0441\u0442\u0438\u043b\u043a\u0438 \u0442\u0430\u043a\u0436\u0435 \u043c\u043e\u0433\u0443\u0442 \u0441\u044b\u0433\u0440\u0430\u0442\u044c \u0432\u0430\u0436\u043d\u0443\u044e \u0440\u043e\u043b\u044c \u0432 \u043a\u043e\u043d\u0442\u0440\u043e\u043b\u0435 \u0437\u0430\u043f\u0430\u0445\u043e\u0432, \u0438\u0441\u0445\u043e\u0434\u044f\u0449\u0438\u0445 \u043e\u0442 \u043a\u043e\u0448\u0430\u0447\u044c\u0438\u0445 \u0442\u043e\u0432\u0430\u0440\u0438\u0449\u0435\u0439.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"6_%D0%A3%D0%B4%D0%B5%D0%BB%D0%B8%D1%82%D0%B5_%D0%B2%D1%80%D0%B5%D0%BC%D1%8F_%D1%83%D0%B1%D0%BE%D1%80%D0%BA%D0%B8_%D0%B7%D0%BE%D0%BD_%D0%B3%D0%B4%D0%B5_%D0%B6%D0%B8%D0%B2%D1%83%D1%82_%D0%B4%D0%BE%D0%BC%D0%B0%D1%88%D0%BD%D0%B8%D0%B5_%D0%B6%D0%B8%D0%B2%D0%BE%D1%82%D0%BD%D1%8B%D0%B5\"><\/span>6. \u0423\u0434\u0435\u043b\u0438\u0442\u0435 \u0432\u0440\u0435\u043c\u044f \u0443\u0431\u043e\u0440\u043a\u0438 \u0437\u043e\u043d, \u0433\u0434\u0435 \u0436\u0438\u0432\u0443\u0442 \u0434\u043e\u043c\u0430\u0448\u043d\u0438\u0435 \u0436\u0438\u0432\u043e\u0442\u043d\u044b\u0435  <span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>\u0420\u0430\u0437\u0440\u0430\u0431\u043e\u0442\u043a\u0430 \u043f\u0440\u043e\u0446\u0435\u0434\u0443\u0440\u044b \u0443\u0431\u043e\u0440\u043a\u0438 \u0441\u043f\u0435\u0446\u0438\u0430\u043b\u044c\u043d\u043e \u0434\u043b\u044f \u043f\u043e\u043c\u0435\u0449\u0435\u043d\u0438\u0439, \u0441\u0432\u044f\u0437\u0430\u043d\u043d\u044b\u0445 \u0441 \u0434\u043e\u043c\u0430\u0448\u043d\u0438\u043c\u0438 \u0436\u0438\u0432\u043e\u0442\u043d\u044b\u043c\u0438, \u0433\u0430\u0440\u0430\u043d\u0442\u0438\u0440\u0443\u0435\u0442, \u0447\u0442\u043e \u044d\u0442\u0438\u043c \u043f\u044f\u0442\u043d\u0430\u043c \u0431\u0443\u0434\u0435\u0442 \u0443\u0434\u0435\u043b\u0435\u043d\u043e \u0434\u043e\u043b\u0436\u043d\u043e\u0435 \u0432\u043d\u0438\u043c\u0430\u043d\u0438\u0435, \u0447\u0442\u043e\u0431\u044b \u043e\u043d\u0438 \u043e\u0441\u0442\u0430\u0432\u0430\u043b\u0438\u0441\u044c \u0447\u0438\u0441\u0442\u044b\u043c\u0438 \u0438 \u0431\u0435\u0437 \u0437\u0430\u043f\u0430\u0445\u0430. \u0421\u0442\u0438\u0440\u043a\u0430 \u043f\u043e\u0434\u0441\u0442\u0438\u043b\u043e\u043a \u0434\u043b\u044f \u0434\u043e\u043c\u0430\u0448\u043d\u0438\u0445 \u0436\u0438\u0432\u043e\u0442\u043d\u044b\u0445, \u0434\u0435\u0437\u0438\u043d\u0444\u0435\u043a\u0446\u0438\u044f \u0441\u0442\u0430\u043d\u0446\u0438\u0439 \u0434\u043b\u044f \u043a\u043e\u0440\u043c\u043b\u0435\u043d\u0438\u044f \u0438 \u043f\u043e\u0434\u0434\u0435\u0440\u0436\u0430\u043d\u0438\u044f \u0447\u0438\u0441\u0442\u043e\u0442\u044b \u0432 \u043b\u043e\u0442\u043a\u0430\u0445 \u0438\u043b\u0438 \u0437\u043e\u043d\u0430\u0445 \u0432\u0430\u043d\u043d\u043e\u0439 \u043a\u043e\u043c\u043d\u0430\u0442\u044b, \u043a\u043e\u0442\u043e\u0440\u044b\u0435 \u043f\u0440\u0435\u0434\u043d\u0430\u0437\u043d\u0430\u0447\u0435\u043d\u044b \u0434\u043b\u044f \u044d\u0442\u043e\u0433\u043e, \u044f\u0432\u043b\u044f\u044e\u0442\u0441\u044f \u0432\u0430\u0436\u043d\u044b\u043c\u0438 \u0437\u0430\u0434\u0430\u0447\u0430\u043c\u0438. \u0421\u043e\u0431\u043b\u044e\u0434\u0435\u043d\u0438\u0435 \u043f\u043e\u0441\u043b\u0435\u0434\u043e\u0432\u0430\u0442\u0435\u043b\u044c\u043d\u043e\u0433\u043e \u0440\u0430\u0441\u043f\u0438\u0441\u0430\u043d\u0438\u044f \u043f\u0440\u0435\u0434\u043e\u0442\u0432\u0440\u0430\u0449\u0430\u0435\u0442 \u043f\u0435\u0440\u0435\u0441\u0438\u043b\u0438\u0432\u0430\u043d\u0438\u0435 \u0437\u0430\u043f\u0430\u0445\u043e\u0432 \u0438 \u0441\u043f\u043e\u0441\u043e\u0431\u0441\u0442\u0432\u0443\u0435\u0442 \u0431\u043e\u043b\u0435\u0435 \u0433\u0438\u0433\u0438\u0435\u043d\u0438\u0447\u0435\u0441\u043a\u043e\u0439 \u043e\u0431\u0449\u0435\u0439 \u0441\u0440\u0435\u0434\u0435.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"7_%D0%92%D1%8B%D0%B1%D0%B8%D1%80%D0%B0%D0%B9%D1%82%D0%B5_%D0%BF%D1%80%D0%B8%D1%80%D0%BE%D0%B4%D0%BD%D1%8B%D0%B5_%D0%BC%D0%B5%D1%82%D0%BE%D0%B4%D1%8B_%D0%B4%D0%B5%D0%B7%D0%BE%D0%B4%D0%BE%D1%80%D0%B0%D1%86%D0%B8%D0%B8\"><\/span>7. \u0412\u044b\u0431\u0438\u0440\u0430\u0439\u0442\u0435 \u043f\u0440\u0438\u0440\u043e\u0434\u043d\u044b\u0435 \u043c\u0435\u0442\u043e\u0434\u044b \u0434\u0435\u0437\u043e\u0434\u043e\u0440\u0430\u0446\u0438\u0438 <span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>\u041d\u0430\u0442\u0443\u0440\u0430\u043b\u044c\u043d\u044b\u0435 \u0434\u0435\u0437\u043e\u0434\u043e\u0440\u0430\u043d\u0442\u044b \u043f\u0440\u0435\u0434\u043b\u0430\u0433\u0430\u044e\u0442 \u0431\u0435\u0437\u043e\u043f\u0430\u0441\u043d\u043e\u0435 \u0438 \u044d\u0444\u0444\u0435\u043a\u0442\u0438\u0432\u043d\u043e\u0435 \u0440\u0435\u0448\u0435\u043d\u0438\u0435 \u043f\u043e \u043f\u043e\u0434\u0434\u0435\u0440\u0436\u0430\u043d\u0438\u044e \u0441\u0432\u0435\u0436\u0435\u0433\u043e \u0437\u0430\u043f\u0430\u0445\u0430 \u0432 \u043a\u0432\u0430\u0440\u0442\u0438\u0440\u0435. \u041f\u043e\u0441\u044b\u043f\u0430\u043d\u0438\u0435 \u043f\u0438\u0449\u0435\u0432\u043e\u0439 \u0441\u043e\u0434\u043e\u0439 \u043d\u0430 \u043a\u043e\u0432\u0440\u044b \u0438 \u043e\u0431\u0438\u0432\u043a\u0443 \u043f\u0435\u0440\u0435\u0434 \u0447\u0438\u0441\u0442\u043a\u043e\u0439 \u043f\u044b\u043b\u0435\u0441\u043e\u0441\u043e\u043c \u043c\u043e\u0436\u0435\u0442 \u043f\u043e\u0433\u043b\u043e\u0442\u0438\u0442\u044c \u0438 \u043d\u0435\u0439\u0442\u0440\u0430\u043b\u0438\u0437\u043e\u0432\u0430\u0442\u044c \u0437\u0430\u043f\u0430\u0445\u0438 \u0431\u0435\u0437 \u0441\u0438\u043d\u0442\u0435\u0442\u0438\u0447\u0435\u0441\u043a\u0438\u0445 \u0430\u0440\u043e\u043c\u0430\u0442\u0438\u0437\u0430\u0442\u043e\u0440\u043e\u0432. \u0414\u043e\u0431\u0430\u0432\u043b\u0435\u043d\u0438\u0435 \u043a\u043e\u043c\u043d\u0430\u0442\u043d\u044b\u0445 \u0440\u0430\u0441\u0442\u0435\u043d\u0438\u0439, \u0431\u0435\u0437\u043e\u043f\u0430\u0441\u043d\u044b\u0445 \u0434\u043b\u044f \u0436\u0438\u0432\u043e\u0442\u043d\u044b\u0445, \u043c\u043e\u0436\u0435\u0442 \u0435\u0449\u0435 \u0431\u043e\u043b\u044c\u0448\u0435 \u043f\u043e\u043c\u043e\u0447\u044c \u0432 \u043e\u0447\u0438\u0441\u0442\u043a\u0435 \u0432\u043e\u0437\u0434\u0443\u0445\u0430, \u0434\u043e\u0431\u0430\u0432\u043b\u044f\u044f \u043a\u0430\u043a \u044d\u0441\u0442\u0435\u0442\u0438\u0447\u0435\u0441\u043a\u0443\u044e \u0446\u0435\u043d\u043d\u043e\u0441\u0442\u044c, \u0442\u0430\u043a \u0438 \u0444\u0443\u043d\u043a\u0446\u0438\u043e\u043d\u0430\u043b\u044c\u043d\u044b\u0435 \u043f\u0440\u0435\u0438\u043c\u0443\u0449\u0435\u0441\u0442\u0432\u0430 \u0434\u043b\u044f \u043e\u0447\u0438\u0441\u0442\u043a\u0438 \u0432\u043e\u0437\u0434\u0443\u0445\u0430 \u0432 \u0432\u0430\u0448\u0435\u0439 \u043a\u0432\u0430\u0440\u0442\u0438\u0440\u0435.<\/p>\n\n\n\n<p>\u041f\u0440\u043e\u0436\u0438\u0432\u0430\u043d\u0438\u0435 \u0441 \u0434\u043e\u043c\u0430\u0448\u043d\u0438\u043c\u0438 \u0436\u0438\u0432\u043e\u0442\u043d\u044b\u043c\u0438 \u0432 \u043a\u0432\u0430\u0440\u0442\u0438\u0440\u0435 \u0442\u0440\u0435\u0431\u0443\u0435\u0442 \u0431\u0430\u043b\u0430\u043d\u0441\u0430 \u043c\u0435\u0436\u0434\u0443 \u0443\u0434\u043e\u0432\u043e\u043b\u044c\u0441\u0442\u0432\u0438\u0435\u043c \u043e\u0442 \u043e\u0431\u0449\u0435\u043d\u0438\u044f \u0438 \u043f\u043e\u0434\u0434\u0435\u0440\u0436\u0430\u043d\u0438\u0435\u043c \u0447\u0438\u0441\u0442\u043e\u0439 \u0441\u0440\u0435\u0434\u044b \u0431\u0435\u0437 \u0437\u0430\u043f\u0430\u0445\u0430. \u0412\u043d\u0435\u0434\u0440\u044f\u044f \u044d\u0442\u0438 \u0441\u0435\u043c\u044c \u0441\u0442\u0440\u0430\u0442\u0435\u0433\u0438\u0439 \u2014 \u043e\u0442 \u0438\u043d\u0432\u0435\u0441\u0442\u0438\u0440\u043e\u0432\u0430\u043d\u0438\u044f \u0432 \u043f\u0440\u0430\u0432\u0438\u043b\u044c\u043d\u044b\u0435 \u0447\u0438\u0441\u0442\u044f\u0449\u0438\u0435 \u0438\u043d\u0441\u0442\u0440\u0443\u043c\u0435\u043d\u0442\u044b \u0434\u043e \u043f\u0440\u0438\u043c\u0435\u043d\u0435\u043d\u0438\u044f \u0435\u0441\u0442\u0435\u0441\u0442\u0432\u0435\u043d\u043d\u044b\u0445 \u043c\u0435\u0442\u043e\u0434\u043e\u0432 \u0434\u0435\u0437\u043e\u0434\u043e\u0440\u0430\u0446\u0438\u0438 \u2014 \u0432\u044b \u043c\u043e\u0436\u0435\u0442\u0435 \u0441\u043e\u0437\u0434\u0430\u0442\u044c \u0436\u0438\u0437\u043d\u0435\u043d\u043d\u043e\u0435 \u043f\u0440\u043e\u0441\u0442\u0440\u0430\u043d\u0441\u0442\u0432\u043e, \u043e\u0442\u0432\u0435\u0447\u0430\u044e\u0449\u0435\u0435 \u043f\u043e\u0442\u0440\u0435\u0431\u043d\u043e\u0441\u0442\u044f\u043c \u043a\u0430\u043a \u0432\u0430\u0441, \u0442\u0430\u043a \u0438 \u0432\u0430\u0448\u0438\u0445 \u0434\u043e\u043c\u0430\u0448\u043d\u0438\u0445 \u0436\u0438\u0432\u043e\u0442\u043d\u044b\u0445. \u0420\u0435\u0433\u0443\u043b\u044f\u0440\u043d\u044b\u0439 \u0443\u0445\u043e\u0434 \u0432 \u0441\u043e\u0447\u0435\u0442\u0430\u043d\u0438\u0438 \u0441 \u043f\u0440\u043e\u0434\u0443\u043c\u0430\u043d\u043d\u044b\u043c \u043f\u043e\u0434\u0445\u043e\u0434\u043e\u043c \u043f\u043e \u0443\u0445\u043e\u0434\u0443 \u0437\u0430 \u0434\u043e\u043c\u0430\u0448\u043d\u0438\u043c\u0438 \u0436\u0438\u0432\u043e\u0442\u043d\u044b\u043c\u0438 \u0433\u0430\u0440\u0430\u043d\u0442\u0438\u0440\u0443\u0435\u0442, \u0447\u0442\u043e \u0432\u0430\u0448\u0430 \u043a\u0432\u0430\u0440\u0442\u0438\u0440\u0430 \u0431\u0443\u0434\u0435\u0442 \u043e\u0441\u0442\u0430\u0432\u0430\u0442\u044c\u0441\u044f \u043f\u0440\u0438\u044f\u0442\u043d\u044b\u043c \u0438 \u0433\u043e\u0441\u0442\u0435\u043f\u0440\u0438\u0438\u043c\u043d\u044b\u043c \u0434\u043e\u043c\u043e\u043c \u0434\u043b\u044f \u043a\u0430\u0436\u0434\u043e\u0433\u043e. \u041f\u043e\u043c\u043d\u0438\u0442\u0435, \u0447\u0442\u043e \u044d\u0444\u0444\u0435\u043a\u0442\u0438\u0432\u043d\u043e\u0441\u0442\u044c \u044d\u0442\u0438\u0445 \u0441\u0442\u0440\u0430\u0442\u0435\u0433\u0438\u0439 \u0437\u0430\u043a\u043b\u044e\u0447\u0430\u0435\u0442\u0441\u044f \u0432 \u0438\u0445 \u043f\u043e\u0441\u043b\u0435\u0434\u043e\u0432\u0430\u0442\u0435\u043b\u044c\u043d\u043e\u043c \u043f\u0440\u0438\u043c\u0435\u043d\u0435\u043d\u0438\u0438 \u0438 \u0432\u044b\u0431\u043e\u0440\u0435 \u043f\u0440\u043e\u0434\u0443\u043a\u0442\u043e\u0432, \u043f\u043e\u0434\u0445\u043e\u0434\u044f\u0449\u0438\u0445 \u0434\u043b\u044f \u0436\u0438\u0432\u043e\u0442\u043d\u044b\u0445, \u0437\u0430\u0449\u0438\u0449\u0430\u044e\u0449\u0438\u0445 \u0437\u0434\u043e\u0440\u043e\u0432\u044c\u0435 \u0438 \u0431\u043b\u0430\u0433\u043e\u043f\u043e\u043b\u0443\u0447\u0438\u0435 \u0432\u0430\u0448\u0438\u0445 \u043b\u044e\u0431\u0438\u043c\u044b\u0445 \u0436\u0438\u0432\u043e\u0442\u043d\u044b\u0445-\u043a\u043e\u043c\u043f\u0430\u043d\u044c\u043e\u043d\u043e\u0432.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0416\u0438\u0437\u043d\u044c \u0432 \u0433\u0430\u0440\u043c\u043e\u043d\u0438\u0438 \u0441 \u0434\u043e\u043c\u0430\u0448\u043d\u0438\u043c\u0438 \u0436\u0438\u0432\u043e\u0442\u043d\u044b\u043c\u0438 \u0432 \u043a\u0432\u0430\u0440\u0442\u0438\u0440\u0435 \u0434\u0430\u0440\u0438\u0442 \u043d\u0435\u043f\u0440\u0435\u0432\u0437\u043e\u0439\u0434\u0435\u043d\u043d\u0443\u044e \u0440\u0430\u0434\u043e\u0441\u0442\u044c \u0438 \u043e\u0431\u0449\u0435\u043d\u0438\u0435, \u043f\u0440\u0435\u0432\u0440\u0430\u0449\u0430\u044f \u043e\u0431\u044b\u0447\u043d\u043e\u0435 \u0436\u0438\u043b\u043e\u0435 \u043f\u0440\u043e\u0441\u0442\u0440\u0430\u043d\u0441\u0442\u0432\u043e \u0432 \u043e\u0431\u0449\u0443\u044e \u0433\u0430\u0432\u0430\u043d\u044c \u0441\u0447\u0430\u0441\u0442\u044c\u044f. \u041e\u0434\u043d\u0430\u043a\u043e \u044d\u0442\u043e \u0441\u043e\u0432\u043c\u0435\u0441\u0442\u043d\u043e\u0435 \u043f\u0440\u043e\u0436\u0438\u0432\u0430\u043d\u0438\u0435 \u0441\u0432\u044f\u0437\u0430\u043d\u043e \u0441\u043e \u0441\u0432\u043e\u0438\u043c\u0438 \u0442\u0440\u0443\u0434\u043d\u043e\u0441\u0442\u044f\u043c\u0438, \u0432 \u0447\u0430\u0441\u0442\u043d\u043e\u0441\u0442\u0438, \u0432 \u0431\u043e\u0440\u044c\u0431\u0435 \u0441 \u043d\u0435\u0438\u0437\u0431\u0435\u0436\u043d\u043e\u0439 \u0448\u0435\u0440\u0441\u0442\u044c\u044e \u0434\u043e\u043c\u0430\u0448\u043d\u0438\u0445 \u0436\u0438\u0432\u043e\u0442\u043d\u044b\u0445 \u0438 \u0432\u044b\u0440\u0430\u0437\u0438\u0442\u0435\u043b\u044c\u043d\u044b\u043c\u0438 \u0437\u0430\u043f\u0430\u0445\u0430\u043c\u0438, \u0441\u043e\u043f\u0440\u043e\u0432\u043e\u0436\u0434\u0430\u044e\u0449\u0438\u043c\u0438 \u043d\u0430\u0448\u0438\u0445 \u043f\u0443\u0448\u0438\u0441\u0442\u044b\u0445 \u0434\u0440\u0443\u0437\u0435\u0439. \u0414\u043e\u043c\u0430\u0448\u043d\u0438\u0435 \u0436\u0438\u0432\u043e\u0442\u043d\u044b\u0435, \u043d\u0435\u0441\u043e\u043c\u043d\u0435\u043d\u043d\u043e, \u043e\u0431\u043e\u0433\u0430\u0449\u0430\u044e\u0442 \u043d\u0430\u0448\u0443 \u0436\u0438\u0437\u043d\u044c, \u043d\u043e \u0431\u0435\u0437 \u0434\u043e\u043b\u0436\u043d\u043e\u0433\u043e \u0443\u0445\u043e\u0434\u0430 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1598,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[43],"tags":[1158,1163,1156,1165,1167,1157,1160,1166,1164,1162],"motype":[45],"moformat":[],"moimportance":[],"class_list":{"0":"post-1604","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-drugoe","8":"tag-7-umnyh-strategij-borby-s-sherstyu-domashnih-zhivotnyh-i-zapahami-v-vashej-kvartire","9":"tag-domashnie-zhivotnye","10":"tag-zhizn-v-garmonii-s-domashnimi-zhivotnymi-v-kvartire-darit-neprevzojdennuyu-radost-i-obshhenie","11":"tag-ispolzujte-moyushhiesya-pledy-i-chehly-dlya-mebeli","12":"tag-nejtralizirujte-zapahi-neposredstvenno-vozle-ih-istochnika","13":"tag-sem-vazhnyh-sovetov-ot-professionalnyh-uborshhikov-kvartir","14":"tag-uborka","15":"tag-uluchshajte-kachestvo-vozduha-pri-pomoshhi-ochistitelej-i-ventilyaczii","16":"tag-ustanovite-posledovatelnyj-poryadok-uborki","17":"tag-chistota","18":"motype-articles"},"_links":{"self":[{"href":"https:\/\/los-angeles-trend.com\/ru\/wp-json\/wp\/v2\/posts\/1604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/los-angeles-trend.com\/ru\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/los-angeles-trend.com\/ru\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/los-angeles-trend.com\/ru\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/los-angeles-trend.com\/ru\/wp-json\/wp\/v2\/comments?post=1604"}],"version-history":[{"count":2,"href":"https:\/\/los-angeles-trend.com\/ru\/wp-json\/wp\/v2\/posts\/1604\/revisions"}],"predecessor-version":[{"id":1607,"href":"https:\/\/los-angeles-trend.com\/ru\/wp-json\/wp\/v2\/posts\/1604\/revisions\/1607"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/los-angeles-trend.com\/ru\/wp-json\/wp\/v2\/media\/1598"}],"wp:attachment":[{"href":"https:\/\/los-angeles-trend.com\/ru\/wp-json\/wp\/v2\/media?parent=1604"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/los-angeles-trend.com\/ru\/wp-json\/wp\/v2\/categories?post=1604"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/los-angeles-trend.com\/ru\/wp-json\/wp\/v2\/tags?post=1604"},{"taxonomy":"motype","embeddable":true,"href":"https:\/\/los-angeles-trend.com\/ru\/wp-json\/wp\/v2\/motype?post=1604"},{"taxonomy":"moformat","embeddable":true,"href":"https:\/\/los-angeles-trend.com\/ru\/wp-json\/wp\/v2\/moformat?post=1604"},{"taxonomy":"moimportance","embeddable":true,"href":"https:\/\/los-angeles-trend.com\/ru\/wp-json\/wp\/v2\/moimportance?post=1604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}