{"id":802,"count":1,"description":"","link":"https:\/\/los-angeles-trend.com\/en\/tag\/began-her-career-in-los-angeles","name":"BEGAN HER CAREER IN LOS ANGELES","slug":"began-her-career-in-los-angeles","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/los-angeles-trend.com\/en\/wp-json\/wp\/v2\/tags\/802","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/los-angeles-trend.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/los-angeles-trend.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/los-angeles-trend.com\/en\/wp-json\/wp\/v2\/posts?tags=802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}