{"id":2278,"count":1,"description":"","link":"https:\/\/los-angeles-trend.com\/en\/tag\/guns-n-roses-concert-tours","name":"Guns N' Roses concert tours","slug":"guns-n-roses-concert-tours","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/los-angeles-trend.com\/en\/wp-json\/wp\/v2\/tags\/2278","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/los-angeles-trend.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/los-angeles-trend.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/los-angeles-trend.com\/en\/wp-json\/wp\/v2\/posts?tags=2278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}