{"id":2086,"count":1,"description":"","link":"https:\/\/los-angeles-trend.com\/en\/tag\/la-german-movie-theater","name":"LA German movie theater","slug":"la-german-movie-theater","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/los-angeles-trend.com\/en\/wp-json\/wp\/v2\/tags\/2086","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/los-angeles-trend.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/los-angeles-trend.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/los-angeles-trend.com\/en\/wp-json\/wp\/v2\/posts?tags=2086"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}