{"id":1514,"count":1,"description":"","link":"https:\/\/los-angeles-trend.com\/en\/tag\/conduct-a-tech-interview-for-new-employees","name":"conduct a tech interview for new employees","slug":"conduct-a-tech-interview-for-new-employees","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/los-angeles-trend.com\/en\/wp-json\/wp\/v2\/tags\/1514","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/los-angeles-trend.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/los-angeles-trend.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/los-angeles-trend.com\/en\/wp-json\/wp\/v2\/posts?tags=1514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}