{"id":1504,"count":1,"description":"","link":"https:\/\/los-angeles-trend.com\/en\/tag\/theater-as-a-cultural-phenomenon","name":"THEATER AS A CULTURAL PHENOMENON","slug":"theater-as-a-cultural-phenomenon","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/los-angeles-trend.com\/en\/wp-json\/wp\/v2\/tags\/1504","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/los-angeles-trend.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/los-angeles-trend.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/los-angeles-trend.com\/en\/wp-json\/wp\/v2\/posts?tags=1504"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}